{"id":3387,"date":"2024-05-11T13:15:00","date_gmt":"2024-05-11T13:15:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=3387"},"modified":"2024-05-12T04:41:50","modified_gmt":"2024-05-12T04:41:50","slug":"se-mantiene-saldo-blanco-en-panteones-municipales-por-dia-de-las-madres-en-soledad","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/05\/11\/se-mantiene-saldo-blanco-en-panteones-municipales-por-dia-de-las-madres-en-soledad\/","title":{"rendered":"Se mantiene saldo blanco en panteones municipales por D\u00eda de las madres, en Soledad"},"content":{"rendered":"\n<ul>\n<li><strong>La Coordinaci\u00f3n de Protecci\u00f3n Civil reporta cero incidencias entre visitantes a los dos cementerios; se tendr\u00e1 presencia este fin de semana.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Coordinaci\u00f3n Municipal de Protecci\u00f3n Civil de Soledad de Graciano S\u00e1nchez informa que las visitas realizadas a los dos Panteones municipales durante el D\u00eda de las Madres transcurren sin incidentes, desde este viernes 10 de mayo, y durante este fin de semana, report\u00e1ndose un saldo blanco en cuanto a seguridad y atenci\u00f3n a la ciudadan\u00eda.<\/p>\n\n\n\n<p>Desde temprana hora, los cementerios \u00abNuestra Se\u00f1ora del Refugio\u00bb y \u00abSe\u00f1or de la Misericordia\u00bb, ambos ubicados en Cabecera municipal, recibieron una gran afluencia de visitantes que acudieron a rendir homenaje a sus seres queridos. Con el objetivo de garantizar la seguridad de las y los asistentes, elementos de Protecci\u00f3n Civil estuvieron desplegados en los dos complejos , coordinando esfuerzos con otras dependencias locales y brindando atenci\u00f3n constante a los visitantes.<\/p>\n\n\n\n<p>Las actividades en los Panteones municipales transcurrieron de manera ordenada y tranquila este viernes y se espera que la afluencia de visitantes permanezca los d\u00edas s\u00e1bado y domingo, por lo que se mantendr\u00e1 la vigilancia, con atenci\u00f3n en auxilios y m\u00e9dica en caso de requerirse, y con ello proporcionar una visita de manera respetuosa y segura.<\/p>\n\n\n\n<p>El horario de visita se mantiene hasta las 7 de la tarde, con el fin de brindar las facilidades a todas las familias de convivir con el recuerdo de sus seres queridos en una tolerancia de tiempo especial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Coordinaci\u00f3n Municipal de Protecci\u00f3n Civil de Soledad de Graciano S\u00e1nchez informa que las visitas realizadas a los dos Panteones municipales durante el D\u00eda de las Madres transcurren sin incidentes, desde este viernes 10 de mayo, y durante este fin de semana, report\u00e1ndose un saldo blanco en cuanto a seguridad y atenci\u00f3n a la ciudadan\u00eda. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3387"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3387"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3387\/revisions"}],"predecessor-version":[{"id":3389,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3387\/revisions\/3389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3388"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}