{"id":33911,"date":"2026-05-13T13:40:00","date_gmt":"2026-05-13T13:40:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=33911"},"modified":"2026-05-13T20:17:29","modified_gmt":"2026-05-13T20:17:29","slug":"ricardo-gallardo-acuerda-reforzar-a-policias-municipales-con-alcaldes-de-la-zona-media","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2026\/05\/13\/ricardo-gallardo-acuerda-reforzar-a-policias-municipales-con-alcaldes-de-la-zona-media\/","title":{"rendered":"Ricardo Gallardo acuerda reforzar a polic\u00edas municipales con alcaldes de la Zona Media"},"content":{"rendered":"\n<ul>\n<li><strong>El Gobernador de San Luis Potos\u00ed solicit\u00f3 a los ediles aplicar los lineamientos recientemente establecidos por el Consejo Estatal de Seguridad P\u00fablica de aumentar un 25 por ciento el n\u00famero de elementos en sus corporaciones.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Ricardo Gallardo Cardona, Gobernador de San Luis Potos\u00ed, sostuvo una reuni\u00f3n de trabajo con alcaldes de la zona Media para fortalecer las estrategias de seguridad p\u00fablica y consolidar corporaciones municipales m\u00e1s eficientes, capacitadas y cercanas a la ciudadan\u00eda.<\/p>\n\n\n\n<p>Durante el encuentro, el Gobernador Ricardo Gallardo acord\u00f3 con las y los presidentes municipales incrementar en un 25 por ciento el n\u00famero de elementos de las polic\u00edas municipales, como parte de los lineamientos recientemente establecidos por el Consejo Estatal de Seguridad P\u00fablica para reforzar la protecci\u00f3n y tranquilidad de las familias potosinas de la regi\u00f3n.<\/p>\n\n\n\n<p>De igual forma, el Gobernador del Estado destac\u00f3 que el Consejo Estatal de Seguridad P\u00fablica determin\u00f3 que los 59 municipios de San Luis Potos\u00ed deber\u00e1n destinar el 20 por ciento de los recursos del Fondo de Aportaciones para el Fortalecimiento de los Municipios y de las Demarcaciones Territoriales (FORTAMUN) 2026 a inversi\u00f3n en materia de seguridad p\u00fablica, priorizando acciones de equipamiento, capacitaci\u00f3n y mejora operativa de las corporaciones locales.<\/p>\n\n\n\n<p>Reiter\u00f3 que, en este cambio que se vive y se siente, la seguridad es una prioridad para su administraci\u00f3n, por lo que convoc\u00f3 a las autoridades municipales a mantener coordinaci\u00f3n permanente con el Gobierno del Estado y las instituciones de seguridad, a fin de seguir avanzando en la construcci\u00f3n de entornos m\u00e1s seguros y en paz para las cuatro regiones de la entidad. Asegur\u00f3 que su administraci\u00f3n seguir\u00e1 apoyando a los municipios con m\u00e1s patrullas y equipamiento para sus elementos policiacos.<\/p>\n\n\n\n<p>Finalmente, Ricardo Gallardo Cardona reafirm\u00f3 su compromiso de continuar impulsando sin l\u00edmites acciones integrales, inversi\u00f3n y estrategias que permitan contar con corporaciones policiales mejor preparadas, equipadas y con mayor capacidad de respuesta, para seguir protegiendo el bienestar y la tranquilidad de las familias potosinas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo Gallardo Cardona, Gobernador de San Luis Potos\u00ed, sostuvo una reuni\u00f3n de trabajo con alcaldes de la zona Media para fortalecer las estrategias de seguridad p\u00fablica y consolidar corporaciones municipales m\u00e1s eficientes, capacitadas y cercanas a la ciudadan\u00eda. Durante el encuentro, el Gobernador Ricardo Gallardo acord\u00f3 con las y los presidentes municipales incrementar en un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33911"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33911"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33911\/revisions"}],"predecessor-version":[{"id":33913,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/33911\/revisions\/33913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/33912"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}