{"id":3510,"date":"2024-05-13T17:40:00","date_gmt":"2024-05-13T17:40:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=3510"},"modified":"2024-05-14T03:58:10","modified_gmt":"2024-05-14T03:58:10","slug":"abren-centros-de-acopio-para-ayudar-a-comunidades-afectadas-por-incendios-forestales","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/05\/13\/abren-centros-de-acopio-para-ayudar-a-comunidades-afectadas-por-incendios-forestales\/","title":{"rendered":"Abren centros de acopio para ayudar a comunidades afectadas por incendios forestales"},"content":{"rendered":"\n<ul>\n<li><strong>Los donativos en especie se pueden entregar en las instalaciones del DIF municipal ubicado en Xicot\u00e9ncatl 1650, o bien en Atenci\u00f3n Ciudadana ubicada en Salvador Nava 1580, de lunes a viernes en un horario de 8 de la ma\u00f1ana a 3 de la tarde<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Gobierno de la Capital, da a conocer que abri\u00f3 dos centros de acopio para que las potosinas y potosinos donen alimentos no perecederos y agua embotellada, en favor de los habitantes de Santa Mar\u00eda del R\u00edo y Tierra Nueva, quienes se han visto afectados por los recientes incendios forestales.<\/p>\n\n\n\n<p>Los donativos en especie se pueden entregar en las instalaciones del DIF municipal ubicado en Xicot\u00e9ncatl 1650, o bien en Atenci\u00f3n Ciudadana ubicada en Salvador Nava 1580, de lunes a viernes en un horario de 8 de la ma\u00f1ana a 3 de la tarde.<\/p>\n\n\n\n<p>Las autoridades de la Capital de San Luis Potos\u00ed hacen el exhorto respetuoso y apelan a la solidaridad de los distintos sectores que integran la sociedad para entregar donativos como alimentos no perecederos y agua embotellada para que posteriormente sean entregados a las familias damnificadas.<\/p>\n\n\n\n<p>Cabe recordar, que el Ayuntamiento capitalino mediante cuadrillas de la Direcci\u00f3n de Protecci\u00f3n Civil Municipal ha apoyado en el control de los incendios en la Sierra de San Miguelito, e igualmente, se encuentra en alerta permanente ante la posibilidad de nuevos siniestros en \u00e1reas forestales.&nbsp;<\/p>\n\n\n\n<p>Datos de car\u00e1cter informativo para conocimiento de la ciudadan\u00eda por ser de inter\u00e9s p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de la Capital, da a conocer que abri\u00f3 dos centros de acopio para que las potosinas y potosinos donen alimentos no perecederos y agua embotellada, en favor de los habitantes de Santa Mar\u00eda del R\u00edo y Tierra Nueva, quienes se han visto afectados por los recientes incendios forestales. Los donativos en especie se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3510"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3510"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3510\/revisions"}],"predecessor-version":[{"id":3512,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3510\/revisions\/3512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3511"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}