{"id":3809,"date":"2024-05-19T15:28:00","date_gmt":"2024-05-19T15:28:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=3809"},"modified":"2024-05-20T01:40:17","modified_gmt":"2024-05-20T01:40:17","slug":"cadetes-del-instituto-de-profesionalizacion-policial-se-capacitan-en-derechos-humanos-de-poblacion-lgbtiq","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/05\/19\/cadetes-del-instituto-de-profesionalizacion-policial-se-capacitan-en-derechos-humanos-de-poblacion-lgbtiq\/","title":{"rendered":"Cadetes del instituto de profesionalizaci\u00f3n policial se capacitan en derechos humanos de poblaci\u00f3n LGBTIQ+"},"content":{"rendered":"\n<p>Cadetes de la segunda generaci\u00f3n del Instituto de Profesionalizaci\u00f3n Policial de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), participaron en una conferencia impartida por la Comisi\u00f3n Estatal de Derechos Humanos (CEDH), y la Asociaci\u00f3n Civil Mujeres Tejiendo Lazos, en el marco del D\u00eda Internacional contra la Homofobia, Lesbofobia, la Transfobia y la Bifobia.<\/p>\n\n\n\n<p>Con el tema \u201cDerecho a la no discriminaci\u00f3n de la poblaci\u00f3n LGBTIQ+\u201d, las y los cadetes ampl\u00edan la perspectiva sobre el respeto y reconocimiento a las identidades diversas, adem\u00e1s de obtener conocimientos para identificar y prevenir la discriminaci\u00f3n, violencia y\/o estigmatizaci\u00f3n de esta comunidad.<\/p>\n\n\n\n<p>Cabe destacar que el Curso Inicial de Formaci\u00f3n de Polic\u00eda de Proximidad para la segunda generaci\u00f3n de cadetes, destaca el desarrollo de conocimientos y habilidades en tres ejes transversales que son: derechos humanos, perspectiva de g\u00e9nero y cultura de la legalidad.<\/p>\n\n\n\n<p>La conferencia fue impartida en la sala de capacitaci\u00f3n del Instituto de Profesionalizaci\u00f3n Policial, donde se abordaron situaciones para atender e intervenir a trav\u00e9s de la perspectiva de la seguridad p\u00fablica basadas en el respeto a los derechos humanos, el contexto y perfil de las personas LGBTIQ+.<\/p>\n\n\n\n<p><strong>Datos de car\u00e1cter informativo para conocimiento de la ciudadan\u00eda por ser de inter\u00e9s p\u00fablico.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadetes de la segunda generaci\u00f3n del Instituto de Profesionalizaci\u00f3n Policial de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), participaron en una conferencia impartida por la Comisi\u00f3n Estatal de Derechos Humanos (CEDH), y la Asociaci\u00f3n Civil Mujeres Tejiendo Lazos, en el marco del D\u00eda Internacional contra la Homofobia, Lesbofobia, la Transfobia y la Bifobia. Con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3809"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3809"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3809\/revisions"}],"predecessor-version":[{"id":3810,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3809\/revisions\/3810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3811"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}