{"id":3815,"date":"2024-05-19T14:20:00","date_gmt":"2024-05-19T14:20:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=3815"},"modified":"2024-05-20T01:51:44","modified_gmt":"2024-05-20T01:51:44","slug":"soledad-de-graciano-sanchez-promueve-inclusion-efectiva-de-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/05\/19\/soledad-de-graciano-sanchez-promueve-inclusion-efectiva-de-personas-con-discapacidad\/","title":{"rendered":"Soledad de Graciano S\u00e1nchez promueve inclusi\u00f3n efectiva de personas con discapacidad"},"content":{"rendered":"\n<ul>\n<li><strong>Con la Consulta P\u00fablica, el municipio genera la oportunidad de identificar y gestionar acciones a favor de este sector en movilidad, interacci\u00f3n social e infraestructura urbana.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Tras el desarrollo de la segunda fase de la Consulta P\u00fablica a Personas con Discapacidad en el municipio de Soledad de Graciano S\u00e1nchez, como parte de la elaboraci\u00f3n del Plan Estatal de Desarrollo (2021-2027), se reconoce la importancia de atender, en coordinaci\u00f3n estatal, las propuestas planteadas en este ejercicio, en temas primordiales como el transporte, la vialidad y la infraestructura, principalmente.&nbsp;<\/p>\n\n\n\n<p>Las personas con discapacidad hoy ocupan un lugar destacado en la agenda p\u00fablica de las instituciones y gobiernos, y Soledad de Graciano S\u00e1nchez destaca y se enorgullece de su compromiso con la inclusi\u00f3n, reflejado en la integraci\u00f3n de personas con discapacidad en al menos 10 \u00e1reas administrativas y operativas del municipio, lo cual es un paso significativo hacia una sociedad m\u00e1s equitativa y justa.<\/p>\n\n\n\n<p>La segunda etapa de la Consulta P\u00fablica, efectuada recientemente en el auditorio municipal fue muy productiva, y cont\u00f3 con la asistencia de personas con distintas dificultades f\u00edsicas y cognitivas, quienes compartieron sus necesidades, destacando la falta de sensibilizaci\u00f3n en operadores de transporte p\u00fablico, quienes suelen obstruir el acceso a personas en silla de ruedas, como una de las m\u00e1s apremiantes.<\/p>\n\n\n\n<p>El DIF Municipal inform\u00f3 que trabajar\u00e1 conjuntamente con las \u00e1reas del Ayuntamiento, como la Direcci\u00f3n de Tr\u00e1nsito y Vialidad, para asegurar que se respeten los espacios de estacionamiento, rampas y pasos peatonales destinados a personas con discapacidad.<\/p>\n\n\n\n<p>Asimismo, se buscar\u00e1 hacer mejoras en la infraestructura vial para facilitar la movilidad y comunicaci\u00f3n, reafirmando as\u00ed su compromiso de trabajar por una ciudad inclusiva y accesible para todas y todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el desarrollo de la segunda fase de la Consulta P\u00fablica a Personas con Discapacidad en el municipio de Soledad de Graciano S\u00e1nchez, como parte de la elaboraci\u00f3n del Plan Estatal de Desarrollo (2021-2027), se reconoce la importancia de atender, en coordinaci\u00f3n estatal, las propuestas planteadas en este ejercicio, en temas primordiales como el transporte, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3815"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3815"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3815\/revisions"}],"predecessor-version":[{"id":3817,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3815\/revisions\/3817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3816"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}