{"id":3821,"date":"2024-05-19T20:03:00","date_gmt":"2024-05-19T20:03:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=3821"},"modified":"2024-05-20T02:43:24","modified_gmt":"2024-05-20T02:43:24","slug":"gran-interes-ciudadano-por-conocer-el-centro-cultural-palacio-municipal-y-sus-galerias","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/05\/19\/gran-interes-ciudadano-por-conocer-el-centro-cultural-palacio-municipal-y-sus-galerias\/","title":{"rendered":"Gran inter\u00e9s ciudadano por conocer el Centro Cultural Palacio Municipal y sus galer\u00edas"},"content":{"rendered":"\n<ul>\n<li><strong>Recinto municipal ha recibido n\u00famero importante de visitantes locales y extranjeros para apreciar la exposici\u00f3n Cambio de Horario; el Museo de Ciudades Hermanas y los \u00f3leos <a>del artista italiano <\/a>Erulo Eroli<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En el marco del D\u00eda Internacional de los Museos celebrado el 28 de mayo, la direcci\u00f3n de Cultura del gobierno de la capital abre las puertas del Centro Cultural Palacio Municipal los d\u00edas 17, 18 y 19 de mayo, para que el p\u00fablico en general conozca las galer\u00edas y sus exposiciones.<\/p>\n\n\n\n<p>Los asistentes apreciaron la exposici\u00f3n: \u201cCambio de Horario\u201d que se expone en las galer\u00edas Tere Caballero y Juan Blanco, el Museo de Ciudades Hermanas, y los frescos de querubines, faunos y cari\u00e1tides en la parte superior de la escalera. Asimismo, el emblem\u00e1tico Escudo de San Luis Rey de Francia, la Capilla del Obispo, la sala de Cabildos (la ex biblioteca), donde se encuentran los \u00f3leos del artista italiano Erulo Eroli.<\/p>\n\n\n\n<p>La direcci\u00f3n de Cultura inform\u00f3 que el Centro Cultural Palacio Municipal es tambi\u00e9n un museo por la gran historia que guarda dentro de cada uno de sus espacios, al haber sido una Prisi\u00f3n, una tienda de raya, la Sociedad Potosina La Lonja y el Palacio Episcopal.<\/p>\n\n\n\n<p><strong>Datos de car\u00e1cter informativo para conocimiento de la ciudadan\u00eda por ser de inter\u00e9s <\/strong><strong>p\u00fablico.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del D\u00eda Internacional de los Museos celebrado el 28 de mayo, la direcci\u00f3n de Cultura del gobierno de la capital abre las puertas del Centro Cultural Palacio Municipal los d\u00edas 17, 18 y 19 de mayo, para que el p\u00fablico en general conozca las galer\u00edas y sus exposiciones. Los asistentes apreciaron la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3821"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3821"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3821\/revisions"}],"predecessor-version":[{"id":3823,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3821\/revisions\/3823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3822"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}