{"id":409,"date":"2024-03-08T14:51:00","date_gmt":"2024-03-08T14:51:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=409"},"modified":"2024-03-09T03:53:43","modified_gmt":"2024-03-09T03:53:43","slug":"gobierno-municipal-soledense-refuerza-servicio-de-recoleccion-de-desechos-2","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/08\/gobierno-municipal-soledense-refuerza-servicio-de-recoleccion-de-desechos-2\/","title":{"rendered":"Gobierno municipal soledense refuerza servicio de recolecci\u00f3n de desechos"},"content":{"rendered":"\n<ul>\n<li><strong>Diariamente, las rutas de los camiones inician operaciones a las 6 de la ma\u00f1ana y llegan a aproximadamente 50 colonias por d\u00eda.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con una flotilla de 12 unidades operativas del \u00e1rea de Servicios Municipales, el Gobierno municipal de Soledad de Graciano S\u00e1nchez contin\u00faa garantizando labores para el servicio de recolecci\u00f3n de desechos s\u00f3lidos urbanos, supervisando una cobertura aproximada de 50 colonias cada d\u00eda, brindado un entorno m\u00e1s limpio y saludable para las y los soledenses.<\/p>\n\n\n\n<p>Dando inicio a su jornada en las primeras horas del d\u00eda, entre las 6 y 7 de la ma\u00f1ana, los camiones se despliegan siguiendo las rutas preestablecidas que han sido dise\u00f1adas para abarcar el mayor territorio posible del municipio; este esquema permite una cobertura eficaz de las \u00e1reas asignadas, procurando as\u00ed que todos los puntos reciban el servicio de recolecci\u00f3n adecuadamente.<\/p>\n\n\n\n<p>Despu\u00e9s de una pausa, las operaciones se reanudan a la una de la tarde, prolong\u00e1ndose hasta las 8 de la noche, asegurando una recolecci\u00f3n extensiva de los residuos generados durante el resto del d\u00eda. Las rutas comprenden de lunes a s\u00e1bado, con personal necesario en los tres turnos preestablecidos.<\/p>\n\n\n\n<p>Para mantener informada a la poblaci\u00f3n sobre los horarios, itinerarios y cualquier cambio que pudiera surgir en el programa de recolecci\u00f3n, el Gobierno Municipal ha establecido l\u00edneas de comunicaci\u00f3n directa con la ciudadan\u00eda, donde las&nbsp; y los interesados en consultar detalles sobre las rutas de recolecci\u00f3n pueden hacerlo llamando al n\u00famero 444-854-50-76, para recibir atenci\u00f3n personalizada y podr\u00e1n resolver todas sus dudas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una flotilla de 12 unidades operativas del \u00e1rea de Servicios Municipales, el Gobierno municipal de Soledad de Graciano S\u00e1nchez contin\u00faa garantizando labores para el servicio de recolecci\u00f3n de desechos s\u00f3lidos urbanos, supervisando una cobertura aproximada de 50 colonias cada d\u00eda, brindado un entorno m\u00e1s limpio y saludable para las y los soledenses. Dando inicio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":410,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/409"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=409"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/409\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/409\/revisions\/411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/410"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}