{"id":4498,"date":"2024-06-01T14:39:00","date_gmt":"2024-06-01T14:39:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=4498"},"modified":"2024-06-02T00:53:08","modified_gmt":"2024-06-02T00:53:08","slug":"gobierno-estatal-llama-a-protegerse-del-calor-durante-las-elecciones","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/06\/01\/gobierno-estatal-llama-a-protegerse-del-calor-durante-las-elecciones\/","title":{"rendered":"Gobierno estatal llama a protegerse del calor durante las elecciones"},"content":{"rendered":"\n<p><strong>\u2022&nbsp; &nbsp; &nbsp; &nbsp;Durante el fin de semana se pronostican temperaturas superiores a los 37 grados, por lo que los Servicios de Salud exhorta a cuidar a ni\u00f1as, ni\u00f1os y adultos mayores<\/strong><\/p>\n\n\n\n<p>Para cuidar la salud de las y los potosinos ante las altas temperaturas que se han presentado en la Entidad, el Poder Ejecutivo del Estado a trav\u00e9s de la Secretar\u00eda de Salud, llam\u00f3 a la ciudadan\u00eda a fortalecer las recomendaciones durante este domingo 2 de junio, ya que se pronostican temperaturas superiores a los 37 grados.<\/p>\n\n\n\n<p>La Secretar\u00eda de Salud&nbsp; recomienda mantener especial vigilancia en ni\u00f1as, ni\u00f1os y adultos mayores, reducir la actividad f\u00edsica como acudir caminando a las urnas durante el horario de mayor calor, de las 12:00 a las 16:00 horas; a las madres y padres que acudir\u00e1n con menores, evitar dejarlos en el veh\u00edculo, mantenerlos en la sombra e hidratarlos frecuentemente; mientras que a las y los funcionarios de casilla y observadores, mantener espacios ventilados, llevar un abanico manual de preferencia y abundante agua.<\/p>\n\n\n\n<p>Se estima que durante el fin de semana, especialmente el pr\u00f3ximo domingo 2 de junio se registren temperaturas de hasta 41 grados cent\u00edgrados en la regi\u00f3n Huasteca y 37 grados para las regiones Centro, Media y Altiplano, por lo que se llama a realizar acciones de prevenci\u00f3n como:&nbsp; mantener la hidrataci\u00f3n, utilizar vestimenta holgada y de colores claros; portar gorra, lentes de sol, protector solar y sombrilla; consumir alimentos livianos y de preferencia acudir a ejercer su derecho al voto por la ma\u00f1ana.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es p\u00fablica, ajena a cualquier inter\u00e9s particular o de alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp; &nbsp; &nbsp; &nbsp;Durante el fin de semana se pronostican temperaturas superiores a los 37 grados, por lo que los Servicios de Salud exhorta a cuidar a ni\u00f1as, ni\u00f1os y adultos mayores Para cuidar la salud de las y los potosinos ante las altas temperaturas que se han presentado en la Entidad, el Poder Ejecutivo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4499,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4498"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4498"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4498\/revisions"}],"predecessor-version":[{"id":4500,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4498\/revisions\/4500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4499"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}