{"id":4811,"date":"2024-06-08T12:45:00","date_gmt":"2024-06-08T12:45:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=4811"},"modified":"2024-06-09T05:44:20","modified_gmt":"2024-06-09T05:44:20","slug":"municipio-soledense-inicia-conformacion-de-tercer-informe-de-actividades","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/06\/08\/municipio-soledense-inicia-conformacion-de-tercer-informe-de-actividades\/","title":{"rendered":"Municipio soledense inicia conformaci\u00f3n de tercer informe de actividades"},"content":{"rendered":"\n<ul>\n<li><strong>A casi tres a\u00f1os de trabajo intenso, hoy hay un Soledad m\u00e1s desarrollado en todos los \u00e1mbitos, que sin duda camina firmemente a convertirse en el mejor municipio del Estado potosino<\/strong><\/li>\n<\/ul>\n\n\n\n<p>El Gobierno Municipal de Soledad de Graciano S\u00e1nchez comenz\u00f3 los preparativos para el Tercer Informe de Actividades, con el cual se rendir\u00e1n cuentas a la poblaci\u00f3n en temas de infraestructura, educaci\u00f3n, seguridad p\u00fablica, programas sociales, salud, servicios p\u00fablicos, entre otros, as\u00ed lo dio a conocer el secretario General del Ayuntamiento, Benjam\u00edn P\u00e9rez \u00c1lvarez.<\/p>\n\n\n\n<p>El funcionario destac\u00f3 que han sido casi tres a\u00f1os de trabajo intenso que muestran un Soledad distinto y m\u00e1s desarrollado en todos los \u00e1mbitos, y que sin duda camina firmemente a convertirse en el mejor municipio del estado potosino; adem\u00e1s agreg\u00f3 que este informe reflejar\u00e1 las obras de alto impacto social que han transformado la vida de las familias.<\/p>\n\n\n\n<p>\u201cDespu\u00e9s de este proceso electoral, ya estamos trabajando en ello; durante esta semana, comenzamos a coordinar con los enlaces de cada direcci\u00f3n y \u00e1rea\u00bb, mencion\u00f3 P\u00e9rez \u00c1lvarez; subray\u00f3 la importancia de realizar este trabajo con el fin de entregar todo en tiempo y forma, cumpliendo con todos los requisitos necesarios.<\/p>\n\n\n\n<p>Asimismo, destac\u00f3 que las principales indicaciones para las \u00e1reas municipales son la cooperaci\u00f3n y la fluidez de la informaci\u00f3n, adem\u00e1s, enfatiz\u00f3 que el enlace responsable de cada \u00e1rea debe estar atento hasta que este proceso concluya, habi\u00e9ndose capacitado previamente en este tema.<\/p>\n\n\n\n<p>Expres\u00f3 que el Gobernador del Estado, Ricardo Gallardo Cardona, ha jugado un papel fundamental en estos \u00faltimos a\u00f1os, brindando apoyo significativo al municipio como programas sociales y la ejecuci\u00f3n de grandes obras que jam\u00e1s se hab\u00edan visto en anteriores administraciones estatales, lo que ha contribuido a construir un Soledad de Graciano S\u00e1nchez completamente en crecimiento y acorde a las nuevas necesidades sociales.<\/p>\n\n\n\n<p>Finalmente, mencion\u00f3 que el Tercer Informe de Actividades ser\u00e1 una oportunidad para reafirmar la cercan\u00eda y compromiso con la ciudadan\u00eda de 300 colonias y localidades que tiene el municipio, de manera que conozcan el buen uso y ejecuci\u00f3n de los recursos p\u00fablicos en la atenci\u00f3n a sus demandas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno Municipal de Soledad de Graciano S\u00e1nchez comenz\u00f3 los preparativos para el Tercer Informe de Actividades, con el cual se rendir\u00e1n cuentas a la poblaci\u00f3n en temas de infraestructura, educaci\u00f3n, seguridad p\u00fablica, programas sociales, salud, servicios p\u00fablicos, entre otros, as\u00ed lo dio a conocer el secretario General del Ayuntamiento, Benjam\u00edn P\u00e9rez \u00c1lvarez. El funcionario [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4811"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4811"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4811\/revisions"}],"predecessor-version":[{"id":4813,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/4811\/revisions\/4813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/4812"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}