{"id":5204,"date":"2024-06-16T11:50:00","date_gmt":"2024-06-16T11:50:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=5204"},"modified":"2024-06-17T05:08:06","modified_gmt":"2024-06-17T05:08:06","slug":"mas-apoyo-con-obras-para-la-zona-metropolitana","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/06\/16\/mas-apoyo-con-obras-para-la-zona-metropolitana\/","title":{"rendered":"M\u00e1s apoyo con obras para la zona metropolitana"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; El Gobernador Ricardo Gallardo anunci\u00f3 que la administraci\u00f3n estatal invertir\u00e1 500 millones de pesos en infraestructura en colonias como Prados Primera y Segunda secci\u00f3n<\/strong><\/p>\n\n\n\n<p>En apoyo a las familias potosinos para que accedan al desarrollo y modernidad, el Gobierno del Estado de San Luis Potos\u00ed cuenta con un fondo por 500 millones de pesos para atender a las colonias que se encuentran abandonadas mediante la rehabilitaci\u00f3n integral de la totalidad de sus calles como Prados Primera y Segunda secci\u00f3n y alrededores, afirm\u00f3 el Gobernador Ricardo Gallardo Cardona.<\/p>\n\n\n\n<p>El Mandatario Estatal dijo que con estas acciones las y los potosinos tendr\u00e1n traslados m\u00e1s c\u00f3modos, \u00e1giles y seguros, pues con la instalaci\u00f3n de modernas luminarias mejorar\u00e1n los entornos en la v\u00eda p\u00fablica aunado a que incrementar\u00e1 la plusval\u00eda en la zona, luego de que por d\u00e9cadas la herencia maldita abandon\u00f3 a las coloniales.<\/p>\n\n\n\n<p>Adem\u00e1s de los programas como \u201cBecas Alimentarias\u201d, \u201cPensiones a Madres Solteras\u201d y \u201cPersonas Adultas Mayores\u201d, la administraci\u00f3n estatal actualmente trabaja en ocho calles y la rehabilitaci\u00f3n integral de las plazas Las \u00c1guilas y El C\u00f3ndor, con lo que se brindan espacios incluyentes para la sana recreaci\u00f3n, lo que permite reconstruir el tejido social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; El Gobernador Ricardo Gallardo anunci\u00f3 que la administraci\u00f3n estatal invertir\u00e1 500 millones de pesos en infraestructura en colonias como Prados Primera y Segunda secci\u00f3n En apoyo a las familias potosinos para que accedan al desarrollo y modernidad, el Gobierno del Estado de San Luis Potos\u00ed cuenta con un fondo por 500 millones de pesos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5204"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5204"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5204\/revisions"}],"predecessor-version":[{"id":5206,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5204\/revisions\/5206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5205"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}