{"id":531,"date":"2024-03-11T17:35:00","date_gmt":"2024-03-11T17:35:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=531"},"modified":"2024-03-12T04:37:07","modified_gmt":"2024-03-12T04:37:07","slug":"mejora-proceso-de-atencion-en-servicios-y-tramites-registrales","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/11\/mejora-proceso-de-atencion-en-servicios-y-tramites-registrales\/","title":{"rendered":"Mejora proceso de atenci\u00f3n en servicios y tr\u00e1mites registrales"},"content":{"rendered":"\n<p>El Poder Ejecutivo del Estado, a trav\u00e9s del Instituto Registral y Catastral (IRC), simplifica los servicios registrales, mediante acciones de mejora continua, por lo que pone a disposici\u00f3n de las y los usuarios la p\u00e1gina, http:\/\/irc.slp.gob.mx\/servicios_en_linea.html donde se pueden solicitar los servicios y tr\u00e1mites registrales que se ofrecen.<\/p>\n\n\n\n<p>La dependencia dio a conocer que para garantizar y proteger los derechos de propiedad de las y los ciudadanos, los servicios que ofrece el IRC se realizan a solicitud de las y los usuarios y se llevan a cabo por personal capacitado con el compromiso y disposici\u00f3n de atender a las familias que m\u00e1s lo requieren, con el \u00fanico objetivo de otorgar certeza jur\u00eddica.<\/p>\n\n\n\n<p>Inform\u00f3 que dentro de los servicios y tr\u00e1mites registrales que se ofrecen est\u00e1n: copia certificada; certificado de existencia\/inexistencia de gravamen; testamento ol\u00f3grafo; consulta y alerta patrimonial.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es de inter\u00e9s p\u00fablico, ajena a cualquier inter\u00e9s particular o de alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Poder Ejecutivo del Estado, a trav\u00e9s del Instituto Registral y Catastral (IRC), simplifica los servicios registrales, mediante acciones de mejora continua, por lo que pone a disposici\u00f3n de las y los usuarios la p\u00e1gina, http:\/\/irc.slp.gob.mx\/servicios_en_linea.html donde se pueden solicitar los servicios y tr\u00e1mites registrales que se ofrecen. La dependencia dio a conocer que para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":532,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/531"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=531"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/531\/revisions"}],"predecessor-version":[{"id":533,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/531\/revisions\/533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/532"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}