{"id":5371,"date":"2024-06-20T12:10:00","date_gmt":"2024-06-20T12:10:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=5371"},"modified":"2024-06-21T03:11:23","modified_gmt":"2024-06-21T03:11:23","slug":"gobierno-municipal-de-soledad-implementa-operativo-emergente-ante-tormenta-tropical-alberto","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/06\/20\/gobierno-municipal-de-soledad-implementa-operativo-emergente-ante-tormenta-tropical-alberto\/","title":{"rendered":"Gobierno municipal de Soledad implementa operativo emergente ante tormenta tropical \u00abAlberto\u00bb"},"content":{"rendered":"\n<ul>\n<li><strong>Diversas dependencias municipales coordinan esfuerzos para atender a la ciudadan\u00eda y mitigar los efectos de las lluvias, incluyendo el traslado de personas, desazolve de drenajes y apoyo y auxilio vial.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Ante las condiciones de lluvia que se registran desde la madrugada de este jueves, derivadas de la tormenta tropical \u201cAlberto\u201d, el Gobierno Municipal de Soledad de Graciano S\u00e1nchez implement\u00f3 un operativo emergente para la atenci\u00f3n a la ciudadan\u00eda desde las primeras horas de este jueves, en el que participan diversas dependencias municipales, como la Coordinaci\u00f3n Municipal de Protecci\u00f3n Civil, Parques y Jardines, Desarrollo Urbano, Ecolog\u00eda, Seguridad P\u00fablica (DGSPM), Tr\u00e1nsito y Polic\u00eda Vial y DIF Municipal.<\/p>\n\n\n\n<p>En el marco de las primeras acciones, la Direcci\u00f3n de Seguridad P\u00fablica Municipal, con el apoyo de unidades patrulla y la Direcci\u00f3n de Ecolog\u00eda, est\u00e1n facilitando el traslado de personas desde la entrada del fraccionamiento Privadas de la Hacienda hasta el interior de las privadas, debido a que esta \u00e1rea est\u00e1 identificada como una zona inundable, y presenta encharcamientos que imposibilitan el ingreso de las personas.<\/p>\n\n\n\n<p>Para mitigar los efectos de la inundaci\u00f3n, la Secretar\u00eda de Desarrollo Urbano y Obras P\u00fablicas (SEDUVOP) del Gobierno Estatal, facilit\u00f3 un equipo vactor para desazolvar del sistema de drenaje en esta misma zona de Privadas de la Hacienda, y con ello permitir un desfogue eficiente del agua de lluvia, generando que el nivel de agua disminuya.<\/p>\n\n\n\n<p>Paralelamente, la Coordinaci\u00f3n de Protecci\u00f3n Civil Municipal brinda apoyo en diversas calles de los fraccionamientos San Lorenzo \u2013donde se est\u00e1 a punto de auxiliar con vactor-, San Luis Uno, Cactus y Quintas de la Hacienda \u2013en la zona de la construcci\u00f3n del colector pluvial-, entre otros, para garantizar la seguridad y bienestar de las y los residentes, con labores de limpieza de alcantarillas. Tambi\u00e9n personal de esta \u00e1rea da monitoreo y vigilancia en la carretera a Matehuala y bulevar R\u00edo Santiago, as\u00ed como en la primaria \u201cGraciano S\u00e1nchez\u201d de la comunidad Enrique Estrada, donde se trabaja en el desazolve de los sistemas de drenaje.<\/p>\n\n\n\n<p>Por su parte, la Direcci\u00f3n de Tr\u00e1nsito y Polic\u00eda Vial mantiene presencia y auxilio en la vialidad de Acceso Norte, debido al cierre vial hacia el Puente Naranja, adem\u00e1s de que se registr\u00f3 una falla en los sem\u00e1foros. En el R\u00edo Santiago, se asisti\u00f3 en el rescate de veh\u00edculos que, aunque no ingresaron al agua, se les dificult\u00f3 su regreso debido a las maniobras en ramales, donde se facilit\u00f3 el uso de gr\u00faas para reincorporar estos veh\u00edculos a vialidades seguras, garantizando as\u00ed la seguridad de los conductores y la fluidez del tr\u00e1fico en la zona.<\/p>\n\n\n\n<p>Se informa a la ciudadan\u00eda que el flujo vehicular en el Bulevar R\u00edo Santiago, a la altura del Puente Naranja, con direcci\u00f3n de San Luis a Soledad, se mantiene en niveles bajos.<\/p>\n\n\n\n<p>El Gobierno Municipal de Soledad de Graciano S\u00e1nchez reitera su compromiso con la seguridad y bienestar de todos los ciudadanos, y continuar\u00e1 monitoreando la situaci\u00f3n para brindar el apoyo necesario en todo momento. Se pide a la poblaci\u00f3n mantenerse alerta e informarse en sitios oficiales de las autoridades del Gobierno del Estado, como municipales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante las condiciones de lluvia que se registran desde la madrugada de este jueves, derivadas de la tormenta tropical \u201cAlberto\u201d, el Gobierno Municipal de Soledad de Graciano S\u00e1nchez implement\u00f3 un operativo emergente para la atenci\u00f3n a la ciudadan\u00eda desde las primeras horas de este jueves, en el que participan diversas dependencias municipales, como la Coordinaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5371"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5371"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5371\/revisions"}],"predecessor-version":[{"id":5373,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5371\/revisions\/5373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5372"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}