{"id":542,"date":"2024-03-12T10:22:00","date_gmt":"2024-03-12T10:22:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=542"},"modified":"2024-03-12T17:25:47","modified_gmt":"2024-03-12T17:25:47","slug":"san-luis-potosi-atractivo-para-inversionistas-japoneses","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/12\/san-luis-potosi-atractivo-para-inversionistas-japoneses\/","title":{"rendered":"San Luis Potos\u00ed atractivo para inversionistas japoneses"},"content":{"rendered":"\n<ul>\n<li><strong>Durante su gira por Jap\u00f3n, el Titular del Ejecutivo Estatal, visit\u00f3 la empresa Taxan, especializada en manufactura de ensambles electr\u00f3nicos\u00a0<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Durante su gira por Jap\u00f3n, el Titular del Poder Ejecutivo Estatal, visit\u00f3 la empresa Taxan, que forma parte del grupo Kaga Electr\u00f3nicas que se especializa en la manufactura de ensambles electr\u00f3nicos para la industria automotriz y que en unas semanas se instalar\u00e1 en territorio potosino generando m\u00e1s de mil 500 empleos para las y los potosinos.<\/p>\n\n\n\n<p>Como parte del trabajo de promoci\u00f3n del potencial econ\u00f3mico y las ventajas competitivas de San Luis Potos\u00ed en Jap\u00f3n, el Mandatario Estatal refrend\u00f3 el compromiso de seguir generando las facilidades para que se sigan instalando m\u00e1s compa\u00f1\u00edas de este pa\u00eds asi\u00e1tico y anunci\u00f3 que a trav\u00e9s de la Secretar\u00eda de Desarrollo Econ\u00f3mico (Sedeco), se impulsar\u00e1 la creaci\u00f3n de una ventanilla \u00fanica para recibir los proyectos de nuevas inversiones.<\/p>\n\n\n\n<p>Tambi\u00e9n particip\u00f3 en el seminario de desarrollo econ\u00f3mico del Estado, en la Embajada de M\u00e9xico en Tokio, donde se promovi\u00f3 las oportunidades de inversi\u00f3n en San Luis Potos\u00ed, resaltando el potencial econ\u00f3mico y las ventajas competitivas del estado, asimismo se comparti\u00f3 el testimonio de la empresa Taxan, con el objetivo de invitar a m\u00e1s empresas japonesas a invertir en la Entidad.<\/p>\n\n\n\n<p>Al t\u00e9rmino del evento, se llev\u00f3 a cabo un networking que permiti\u00f3 un acercamiento directo entre las empresas y el Gobernador, fortaleciendo as\u00ed los lazos comerciales entre San Luis Potos\u00ed y Jap\u00f3n.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es de inter\u00e9s p\u00fablico, ajena a cualquier inter\u00e9s particular o alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante su gira por Jap\u00f3n, el Titular del Poder Ejecutivo Estatal, visit\u00f3 la empresa Taxan, que forma parte del grupo Kaga Electr\u00f3nicas que se especializa en la manufactura de ensambles electr\u00f3nicos para la industria automotriz y que en unas semanas se instalar\u00e1 en territorio potosino generando m\u00e1s de mil 500 empleos para las y los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/542"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=542"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/542\/revisions"}],"predecessor-version":[{"id":544,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/542\/revisions\/544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/543"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}