{"id":5424,"date":"2024-06-21T21:20:00","date_gmt":"2024-06-21T21:20:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=5424"},"modified":"2024-06-22T19:36:07","modified_gmt":"2024-06-22T19:36:07","slug":"logra-santas-del-potosi-calificacion-a-playoffs-de-la-liga-caliente-mx-lnbp","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/06\/21\/logra-santas-del-potosi-calificacion-a-playoffs-de-la-liga-caliente-mx-lnbp\/","title":{"rendered":"Logra Santas del Potos\u00ed calificaci\u00f3n a playoffs de la Liga Caliente .MX LNBP"},"content":{"rendered":"\n<ul>\n<li><strong>La quinteta celestial venci\u00f3 a Panteras Femenil con marcador de 89 a 78, qued\u00e1ndose con los dos juegos de la serie.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Las Santas del Potos\u00ed se quedaron con la serie ante Panteras Femenil, al vencerlas con marcador de 89 a 78, en un duelo celebrado en la duela del auditorio Miguel Barrag\u00e1n, una victoria que le&nbsp; permite&nbsp; a la quinteta celestial su calificaci\u00f3n a los playoffs 2024 de la&nbsp; Liga Caliente .MX LNBP Femenil.<\/p>\n\n\n\n<p>En el primer periodo las Santas del Potos\u00ed pr\u00e1cticamente le pasaron por encima a las Panteras de Aguascalientes, pues desde el inicio del partido dominaron, terminando por sacar una ventaja de 17 puntos sobre las hidroc\u00e1lidas al terminar 31 a 17; Para el segundo periodo el dominio continu\u00f3, lo que llev\u00f3 a la quinteta celestial a irse adelante en el marcador 25 puntos, al irse al medio tiempo 61 a 36.<\/p>\n\n\n\n<p>Para el tercer periodo Panteras Femenil intent\u00f3 acortar la ventaja, aunque la diferencia sigui\u00f3 siendo amplia, al quedar 71 a 56; Sin embargo en el ultimo cuarto se acercaron peligrosamente, disminuyendo la ventaja a un solo d\u00edgito, sin embargo fue en el ultimo cuarto cuando se acercaron a solo cinco puntos, aunque las potosinas lograron reaccionar y al final lograron quedarse con la victoria.<\/p>\n\n\n\n<p>En este duelo destac\u00f3 Hilary Mart\u00ednez que brill\u00f3 en la duela con 21 puntos, 7 rebotes y 5 asistencias, Aniya Thomas&nbsp; con 19 puntos, al igual que Shaiquel Mcgruder con los mismos puntos,&nbsp; como las mejores jugadoras de Santas del Potos\u00ed,&nbsp; mientras que las Panteras Femenil tuvieron en Tinara Moore a su mejor jugadora con 22 puntos, 13 rebotes y 4 asistencia.<\/p>\n\n\n\n<p>Luego de esta victoria Santas del Potos\u00ed cerrar\u00e1 la temporada enfrentando a Abejas de Le\u00f3n en la capital del zapato, en tanto que Panteras no tendr\u00e1 un cierre sencillo, pues estar\u00e1 recibiendo en Aguascalientes a las Adelitas de Chihuahua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Santas del Potos\u00ed se quedaron con la serie ante Panteras Femenil, al vencerlas con marcador de 89 a 78, en un duelo celebrado en la duela del auditorio Miguel Barrag\u00e1n, una victoria que le&nbsp; permite&nbsp; a la quinteta celestial su calificaci\u00f3n a los playoffs 2024 de la&nbsp; Liga Caliente .MX LNBP Femenil. En el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5425,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[5],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5424"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5424"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5424\/revisions"}],"predecessor-version":[{"id":5426,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5424\/revisions\/5426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5425"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}