{"id":548,"date":"2024-03-12T18:47:06","date_gmt":"2024-03-12T18:47:06","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=548"},"modified":"2024-03-12T18:47:06","modified_gmt":"2024-03-12T18:47:06","slug":"proteger-salud-publica-mision-de-operativo-cuaresma-2024","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/12\/proteger-salud-publica-mision-de-operativo-cuaresma-2024\/","title":{"rendered":"Proteger salud p\u00fablica, misi\u00f3n de Operativo Cuaresma 2024"},"content":{"rendered":"\n<ul>\n<li><strong>Se ha destruido un total de 1.8 kilogramos de producto del mar por inadecuada conservaci\u00f3n y cinco purificadoras de agua se suspendieron temporalmente<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con el objetivo de proteger la salud de las y los potosinos, el Poder Ejecutivo del Estado de San Luis Potos\u00ed, a trav\u00e9s de la Secretar\u00eda de Salud, ha destruido 1.8 kilogramos de producto del mar y ha realizado cinco suspensiones a purificadoras de agua y contin\u00faa con revisiones de control sanitario a expendedores de productos del mar tanto preparados como crudos, as\u00ed como la vigilancia sanitaria a purificadoras de agua y f\u00e1bricas de hielo.<\/p>\n\n\n\n<p>La Comisi\u00f3n Estatal para la Protecci\u00f3n Contra Riesgos Sanitarios (Coepris), realizar\u00e1 acciones de vigilancia hasta el 7 de abril y se intensifican en los municipios mediante visitas de control sanitario, muestreos de producto y asesor\u00edas a pescader\u00edas, restaurantes de pescados y mariscos, ostioner\u00edas as\u00ed como a plantas purificadoras, para evitar enfermedades intestinales o intoxicaciones.<\/p>\n\n\n\n<p>La dependencia ha realizado 180 visitas de control sanitario, y se han aplicado 78 muestreos de productos lo que deriv\u00f3 en la suspensi\u00f3n temporal de cinco purificadoras de agua, as\u00ed como la destrucci\u00f3n de 1.8 kilogramos de producto del mar. Adem\u00e1s de asesor\u00eda a 243 manejadores de alimentos, principalmente aquellos en sitios tur\u00edsticos, 11 cursos con 241 asistentes y 61 pl\u00e1ticas a pescadores y expendedores de productos del mar con 341 participantes.<\/p>\n\n\n\n<p>El consumo de productos del mar en mal estado pueden ocasionar infecciones e intoxicaciones alimentarias, destacando diarrea, n\u00e1useas, v\u00f3mitos y dolores abdominales como s\u00edntomas y tambi\u00e9n reacciones al\u00e9rgicas que pueden presentarse con cosquilleo, inflamaci\u00f3n de boca y garganta.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es de inter\u00e9s p\u00fablico, ajena a cualquier inter\u00e9s particular o alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de proteger la salud de las y los potosinos, el Poder Ejecutivo del Estado de San Luis Potos\u00ed, a trav\u00e9s de la Secretar\u00eda de Salud, ha destruido 1.8 kilogramos de producto del mar y ha realizado cinco suspensiones a purificadoras de agua y contin\u00faa con revisiones de control sanitario a expendedores de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/548"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/548\/revisions"}],"predecessor-version":[{"id":550,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/548\/revisions\/550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/549"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}