{"id":5934,"date":"2024-07-04T12:28:00","date_gmt":"2024-07-04T12:28:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=5934"},"modified":"2024-07-04T19:40:28","modified_gmt":"2024-07-04T19:40:28","slug":"ayuntamiento-de-soledad-coordina-seguimiento-a-consulta-publica-de-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/07\/04\/ayuntamiento-de-soledad-coordina-seguimiento-a-consulta-publica-de-personas-con-discapacidad\/","title":{"rendered":"Ayuntamiento de Soledad coordina seguimiento a consulta p\u00fablica de personas con discapacidad"},"content":{"rendered":"\n<p><strong>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La tercera fase de la Consulta se realizar\u00e1 en el municipio este mi\u00e9rcoles a las 11 de la ma\u00f1ana, en el Auditorio municipal.<\/strong><\/p>\n\n\n\n<p>Con el objetivo de preparar y dar seguimiento puntual a la \u00faltima etapa de la Consulta P\u00fablica para Personas con Discapacidad, convocada por el Comit\u00e9 de Planeaci\u00f3n para el Desarrollo del Estado (COPLADE), programada para el pr\u00f3ximo 11 de julio; este mi\u00e9rcoles, se llev\u00f3 a cabo una reuni\u00f3n estrat\u00e9gica en la que participaron las \u00e1reas involucradas del Ayuntamiento de Soledad de Graciano S\u00e1nchez.<\/p>\n\n\n\n<p>En este encuentro, se cont\u00f3 con la integraci\u00f3n de \u00e1reas clave como Ecolog\u00eda, Derechos Humanos y Desarrollo Econ\u00f3mico, quienes se sumaron a este esfuerzo para asegurar que las necesidades y opiniones de las personas con discapacidad sean debidamente atendidas y reflejadas en las pol\u00edticas p\u00fablicas, y que exista una armon\u00eda de trabajo entre los niveles de gobierno estatal y municipal.<\/p>\n\n\n\n<p>La Alcaldesa Araceli Mart\u00ednez P\u00e9rez, quien encabez\u00f3 esta reuni\u00f3n, destac\u00f3 el compromiso continuo del Gobierno Municipal con la inclusi\u00f3n. \u00abComo municipio, estamos comprometidos a cumplir con este ejercicio ciudadano, que aporta mucho al municipio, independientemente de ser una disposici\u00f3n legal y administrativa de Gobierno del Estado, lo cual es fundamental para integrar y hacer m\u00e1s a favor de las personas con discapacidad de manera efectiva\u201d, manifest\u00f3.<\/p>\n\n\n\n<p>Mencion\u00f3 que la segunda etapa de la Consulta revel\u00f3 las necesidades espec\u00edficas de este sector de la poblaci\u00f3n, las cuales se han canalizado a cada departamento correspondiente para su conocimiento y tomar en cuenta las necesidades, as\u00ed como las acciones cumplidas en su \u00e1mbito; esto facilitar\u00e1 que la pr\u00f3xima administraci\u00f3n contin\u00fae este camino con un gobierno a\u00fan m\u00e1s inclusivo.&nbsp;<\/p>\n\n\n\n<p>Por su parte, la Contralora Interna, Mariana S\u00e1nchez Mart\u00ednez dijo que la tercera y \u00faltima etapa de esta Consulta tendr\u00e1 el objetivo de generar foros de atenci\u00f3n a las peticiones identificadas, y socializarlas con este sector de la poblaci\u00f3n, coordinando acciones espec\u00edficas seg\u00fan el \u00e1rea correspondiente.<\/p>\n\n\n\n<p>El pr\u00f3ximo foro, programado para el mi\u00e9rcoles 11 de julio a las 11 de la ma\u00f1ana, en el Auditorio de la Presidencia Municipal, est\u00e1 abierto a toda la ciudadan\u00eda de este sector, y en \u00e9l se presentar\u00e1n evidencias documentales para respaldar las propuestas y necesidades identificadas, adem\u00e1s, se realizar\u00e1 una solicitud especial a la Secretar\u00eda de Comunicaciones y Transportes (SCT) para concientizar a transportistas y taxistas sobre la importancia de facilitar el traslado de personas con discapacidad y el uso adecuado de espacios reservados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La tercera fase de la Consulta se realizar\u00e1 en el municipio este mi\u00e9rcoles a las 11 de la ma\u00f1ana, en el Auditorio municipal. Con el objetivo de preparar y dar seguimiento puntual a la \u00faltima etapa de la Consulta P\u00fablica para Personas con Discapacidad, convocada por el Comit\u00e9 de Planeaci\u00f3n para el Desarrollo del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5934"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5934"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5934\/revisions"}],"predecessor-version":[{"id":5936,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5934\/revisions\/5936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5935"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}