{"id":6152,"date":"2024-07-08T17:00:00","date_gmt":"2024-07-08T17:00:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=6152"},"modified":"2024-07-09T02:55:00","modified_gmt":"2024-07-09T02:55:00","slug":"parques-estatales-concentran-mas-eventos-para-las-y-los-potosinos","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/07\/08\/parques-estatales-concentran-mas-eventos-para-las-y-los-potosinos\/","title":{"rendered":"Parques estatales concentran m\u00e1s eventos para las y los potosinos"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Este fin de semana, los Parques Tangamanga I y II de la capital y Las Camelias del Altiplano, fueron sede de diversas actividades que atrajeron a cerca de 100 mil personas<\/strong><\/p>\n\n\n\n<p>Los parques Tangamanga I y II de la capital y Las Camelias de Matehuala, se consolidan como puntos de referencia para eventos recreativos, deportivos y culturales, que, durante el pasado fin de semana, atrajeron a cerca de 100 mil personas.<\/p>\n\n\n\n<p>Ana Rosa Pineda Guel, titular de los Centros Estatales de Cultura y Recreaci\u00f3n Tangamanga (Cecurt), resalt\u00f3 que, con el apoyo del Gobernador del Estado, Ricardo Gallardo Cardona, San Luis Potos\u00ed cuenta como nunca, con actividades para todas las edades y todos los gustos, como este s\u00e1bado 6 y domingo 7 de julio, que el Parque Japon\u00e9s en el Tangamanga recibi\u00f3 al \u201cTanabata\u201d, Festival de las Estrellas en Jap\u00f3n, donde hubo venta de bebidas, alimentos y dulces japoneses.<\/p>\n\n\n\n<p>Detall\u00f3 que, en esta actividad, congreg\u00f3 a m\u00e1s de 13 mil personas, que participaron con la escritura en papeles para posteriormente colgarlos en bamb\u00fas, creando un ambiente muy colorido. La festividad conmemora el s\u00e9ptimo d\u00eda del s\u00e9ptimo mes lunar del calendario lunisolar en Jap\u00f3n y significa la llegada de la Festividad de las Estrellas.<\/p>\n\n\n\n<p>Por su parte, dijo que se celebr\u00f3 el 18\u00b0 Aniversario del Mustang Club San Luis, con actividades&nbsp; en el aut\u00f3dromo del parque Tangamanga II, una exhibici\u00f3n de autos Mustang y la participaci\u00f3n de 30 clubs locales y for\u00e1neos provenientes de Monterrey, Zacatecas, Aguascalientes, Le\u00f3n, Tamaulipas, Guerrero, Quer\u00e9taro, Ciudad de M\u00e9xico, Tampico y Saltillo, reuniendo un total de 200 autos que reuni\u00f3 a entusiastas y coleccionistas de todo el pa\u00eds, destacando la participaci\u00f3n del impresionante Shelby Cobra modelo 1964.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Este fin de semana, los Parques Tangamanga I y II de la capital y Las Camelias del Altiplano, fueron sede de diversas actividades que atrajeron a cerca de 100 mil personas Los parques Tangamanga I y II de la capital y Las Camelias de Matehuala, se consolidan como puntos de referencia para eventos recreativos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6152"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6152"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6152\/revisions"}],"predecessor-version":[{"id":6154,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6152\/revisions\/6154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/6153"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}