{"id":6340,"date":"2024-07-13T15:50:00","date_gmt":"2024-07-13T15:50:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=6340"},"modified":"2024-07-13T23:08:10","modified_gmt":"2024-07-13T23:08:10","slug":"slp-sera-sede-de-encuentro-nacional-de-personas-con-discapacidad-visual","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/07\/13\/slp-sera-sede-de-encuentro-nacional-de-personas-con-discapacidad-visual\/","title":{"rendered":"SLP ser\u00e1 sede de Encuentro Nacional de Personas con Discapacidad Visual"},"content":{"rendered":"\n<ul>\n<li><strong>Del 17 al 21 de julio, la Entidad recibir\u00e1 a personas provenientes de siete estados<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En apoyo a la pol\u00edtica de inclusi\u00f3n, y para impulsar un turismo sin barreras para las personas con discapacidad, del 17 al 21 de julio, San Luis Potos\u00ed ser\u00e1 sede el Octavo Encuentro Nacional de Personas con Discapacidad Visual con sede en el Museo de la M\u00e1scara, que recibir\u00e1 a cientos de personas provenientes de diferentes estados del pa\u00eds, anunci\u00f3 la Secretar\u00eda de Turismo (Sectur).<\/p>\n\n\n\n<p>En cumplimiento a la instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona, la Sectur trabaja en coordinaci\u00f3n con la asociaci\u00f3n \u201cTrabajemos por una Nueva Luz\u201d, que organiza este evento cuyo objetivo es garantizar que las personas con discapacidad visual puedan ejercer sus derechos de igualdad y acceso al turismo, la cultura y la recreaci\u00f3n.<\/p>\n\n\n\n<p>Detall\u00f3 la dependencia que este encuentro busca concientizar sobre el turismo inclusivo para que hoteles, restaurantes, parajes, museos y sitios de inter\u00e9s, cuenten con rampas, ascensores con botones braille o salidas de audio, gu\u00edas podot\u00e1ctiles, entre otro equipamiento para que las personas con discapacidad disfruten de una mejor experiencia al vacacionar.<\/p>\n\n\n\n<p>Adem\u00e1s, el encuentro generar\u00e1 una importante derrama econ\u00f3mica en San Luis Potos\u00ed con el registro de una buena ocupaci\u00f3n hotelera y de las actividades comerciales, pues participar\u00e1n personas provenientes de Nuevo Le\u00f3n, Hidalgo, Guanajuato, Michoac\u00e1n, Quer\u00e9taro, Baja California y Ciudad de M\u00e9xico, lo que fortalecer\u00e1 el turismo social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En apoyo a la pol\u00edtica de inclusi\u00f3n, y para impulsar un turismo sin barreras para las personas con discapacidad, del 17 al 21 de julio, San Luis Potos\u00ed ser\u00e1 sede el Octavo Encuentro Nacional de Personas con Discapacidad Visual con sede en el Museo de la M\u00e1scara, que recibir\u00e1 a cientos de personas provenientes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6340"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6340"}],"version-history":[{"count":2,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6340\/revisions"}],"predecessor-version":[{"id":6343,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6340\/revisions\/6343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/6341"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}