{"id":662,"date":"2024-03-15T16:10:00","date_gmt":"2024-03-15T16:10:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=662"},"modified":"2024-03-16T02:13:32","modified_gmt":"2024-03-16T02:13:32","slug":"en-plaza-del-carmen-las-actividades-infantiles-del-festival-internacional-san-luis-en-primavera","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/15\/en-plaza-del-carmen-las-actividades-infantiles-del-festival-internacional-san-luis-en-primavera\/","title":{"rendered":"\u00a1En Plaza del Carmen las actividades infantiles del Festival Internacional San Luis en Primavera!"},"content":{"rendered":"\n<ul>\n<li><strong>Espect\u00e1culos de teatro, teatro clown, circense, zanqueros, t\u00edteres y animaci\u00f3n que podr\u00e1n ser disfrutados por chicos y grandes.<\/strong><\/li>\n\n\n\n<li><strong>\u201cCirco Drag\u00f3n\u201d; \u201cCarret\u00f3n del Desierto\u201d; \u201cLos Locos Adams\u201d; \u201cPladeta Verne\u201d y \u201cDany Torres y Carlos Gael\u201d, estar\u00e1n presentes en la programaci\u00f3n infantil para ni\u00f1as y ni\u00f1os.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Plaza del Carmen y las calles del Centro Hist\u00f3rico ser\u00e1n sedes del programa infantil del Festival Internacional San Luis en Primavera, por lo que los peque\u00f1os tendr\u00e1n en vacaciones de Semana Santa, actividades para que puedan disfrutar con sus padres y hermanos, as\u00ed como para quienes est\u00e9n de visita en la ciudad en esta temporada.<\/p>\n\n\n\n<p>El H. Ayuntamiento de San Luis Potos\u00ed, dan a conocer que la actividad infantil en Plaza del Carmen, donde se instalar\u00e1 un escenario:<\/p>\n\n\n\n<ul>\n<li>Domingo 24 de marzo, 18:30 horas. Obra \u201cAvatar\u201d por parte de Circo Drag\u00f3n.<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Lunes 25 de marzo, 18:30 horas. Obra \u201cObs\u00e9rvame\u201d con la Compa\u00f1\u00eda Seres. Grupo de teatro con discapacidad visual y motriz.<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Martes 26 de marzo, 12:00 horas. La Caja Errante (T\u00edteres) con la agrupaci\u00f3n Carret\u00f3n del Desierto.<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Martes 26 de marzo, 18:30 horas. Obra \u201cLos locos Adams\u201d, con la agrupaci\u00f3n K\u00f6et\u00fcs.<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Mi\u00e9rcoles 27 de marzo, 12:00 horas. Se presentan Dany Torres y Carlos Gael. Talento infantil.<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Mi\u00e9rcoles 27 de marzo, 18:30 horas. Obra \u201cPladeta Verne\u201d, con la agrupaci\u00f3n Pneumus.<\/li>\n<\/ul>\n\n\n\n<p><strong>Consulta la programaci\u00f3n:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-san-luis-en-primavera wp-block-embed-san-luis-en-primavera\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"mSAlqb7OCJ\"><a href=\"https:\/\/sanluisenprimavera.com\/\">Home<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Home&#8221; &#8212; San Luis en Primavera\" src=\"https:\/\/sanluisenprimavera.com\/embed\/#?secret=54J2vYeZPU#?secret=mSAlqb7OCJ\" data-secret=\"mSAlqb7OCJ\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Se comparte esta informaci\u00f3n por su relevancia para el p\u00fablico en general; no est\u00e1 influenciada por intereses individuales o afiliaciones pol\u00edticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Plaza del Carmen y las calles del Centro Hist\u00f3rico ser\u00e1n sedes del programa infantil del Festival Internacional San Luis en Primavera, por lo que los peque\u00f1os tendr\u00e1n en vacaciones de Semana Santa, actividades para que puedan disfrutar con sus padres y hermanos, as\u00ed como para quienes est\u00e9n de visita en la ciudad en esta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/662"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=662"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/662\/revisions"}],"predecessor-version":[{"id":664,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/662\/revisions\/664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/663"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}