{"id":710,"date":"2024-03-17T12:21:00","date_gmt":"2024-03-17T12:21:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=710"},"modified":"2024-03-18T07:25:46","modified_gmt":"2024-03-18T07:25:46","slug":"en-san-luis-potosi-el-pan-tiene-equipo-de-primera-para-ganar","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/17\/en-san-luis-potosi-el-pan-tiene-equipo-de-primera-para-ganar\/","title":{"rendered":"En San Luis Potos\u00ed el PAN tiene equipo de primera para ganar"},"content":{"rendered":"\n<p>El Secretario General en funciones de Presidente del Partido Acci\u00f3n Nacional, Enrique Dahud asegur\u00f3 que se encuentran listos para las elecciones del 2 de junio en la capacitaci\u00f3n \u201cPrep\u00e1rate para ganar desde lo local\u201d que se llev\u00f3 a cabo con la finalidad de estar listos para la contienda electoral.<\/p>\n\n\n\n<p>Agradeci\u00f3 la presencia dela candidata al Senado Ver\u00f3nica Rodr\u00edguez y su compa\u00f1era de f\u00f3rmula Estela Arriaga, a los candidatos a diputados locales del distrito 4, Jaime Waldo; del distrito 8, Aranza Puente; del distrito 6, Gerardo Aldaco, del distrito 7, Perla Garza; y del distrito 15, Karen Mac\u00edas. As\u00ed como, a los candidatos a diputados federales del distrito 2, Wendy Rodr\u00edguez; del distrito 5, David Azuara; y del distrito 6, Mei Ham.<\/p>\n\n\n\n<p>En el evento tambi\u00e9n estuvieron los candidatos a presidentes municipales: de San Luis Potos\u00ed, Enrique Galindo; Xilitla, Javier Pacheco; San Mart\u00edn, Santiago Zumaya; \u00c9bano Jos\u00e9 Ordaz; C\u00e1rdenas, Rebeca Medina; Zaragoza, Mar\u00eda Mart\u00ednez; El Naranjo, Andr\u00e9s Mart\u00ednez; Ciudad del Ma\u00edz, Silvestre Carrizales; Alaquines, Iveth Bilchis; Jos\u00e9 Catillo, Rioverde; Celina Cuevas, Charcas; Ra\u00fal Ortega, Matehuala; Fulgencio P\u00e9rez, Santa Mar\u00eda del R\u00edo; Juanis Cabrera, San Ciro de Acosta; Patricia Oca\u00f1a, Coxcatl\u00e1n.<\/p>\n\n\n\n<p>Durante su discurso subray\u00f3 que cuando Acci\u00f3n Nacional gobierna, los ciudadanos lo dicen y ven los resultados, por lo que est\u00e1 seguro que, en San Luis Potos\u00ed, se van a tener los mejores resultados de la historia.<\/p>\n\n\n\n<p>\u201cEs momento de hacer lo que nos toca, y trabajar en equipo para que no exista la manera de que lo peor de la pol\u00edtica, que es Morena, tenga oportunidad de llegar\u201d.<\/p>\n\n\n\n<p>Por su parte, el alcalde de la capital, quien busca la reelecci\u00f3n, Enrique Galindo, agradeci\u00f3 al PAN la oportunidad de confiar para encabezar este proceso en busca de la alcald\u00eda capitalina y se\u00f1al\u00f3 que se ha hecho un gran equipo.<\/p>\n\n\n\n<p>La candidata al Senado, Ver\u00f3nica Rodr\u00edguez&nbsp; puntualiz\u00f3 que se est\u00e1 trabajando en la calle, escuchando a los ciudadanos para poder llevar a la coalici\u00f3n \u201cFuerza y Coraz\u00f3n por M\u00e9xico\u201d y a su candidata X\u00f3chitl G\u00e1lvez para que se convierta en la primera presidenta del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Secretario General en funciones de Presidente del Partido Acci\u00f3n Nacional, Enrique Dahud asegur\u00f3 que se encuentran listos para las elecciones del 2 de junio en la capacitaci\u00f3n \u201cPrep\u00e1rate para ganar desde lo local\u201d que se llev\u00f3 a cabo con la finalidad de estar listos para la contienda electoral. Agradeci\u00f3 la presencia dela candidata al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[13],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/710"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/710\/revisions"}],"predecessor-version":[{"id":712,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/710\/revisions\/712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/711"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}