{"id":742,"date":"2024-03-18T12:06:00","date_gmt":"2024-03-18T12:06:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=742"},"modified":"2024-03-18T20:08:16","modified_gmt":"2024-03-18T20:08:16","slug":"gobierno-municipal-de-soledad-mantiene-trabajo-operativo-en-dia-festivo","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/18\/gobierno-municipal-de-soledad-mantiene-trabajo-operativo-en-dia-festivo\/","title":{"rendered":"Gobierno municipal de Soledad mantiene trabajo operativo en d\u00eda festivo"},"content":{"rendered":"\n<ul>\n<li><strong>Dependencias esenciales brindan atenci\u00f3n a la poblaci\u00f3n en este d\u00eda de asueto.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con la finalidad de mantener activa la atenci\u00f3n a la ciudadan\u00eda, el Gobierno Municipal de Soledad de Graciano S\u00e1nchez garantiza la prestaci\u00f3n de servicios p\u00fablicos en sus \u00e1reas operativas, de emergencia y exilio, as\u00ed como de tr\u00e1mites fundamentales en este d\u00eda de asueto, inform\u00f3 la Contralor\u00eda Interna.<\/p>\n\n\n\n<p>Este lunes 18 de marzo, considerado como descanso por la conmemoraci\u00f3n del natalicio de Benito Ju\u00e1rez Garc\u00eda, las dependencias municipales que brindan servicios esenciales a la poblaci\u00f3n, como Seguridad P\u00fablica Municipal, Protecci\u00f3n Civil, Aseo P\u00fablico, Servicios Municipales, Servicios Generales, Servicio M\u00e9dico, Funeraria municipal y Catastro, por mencionar algunas, mantienen actividades en horario normal.<\/p>\n\n\n\n<p>Personal asignado a la Contralor\u00eda Interna realiz\u00f3 una inspecci\u00f3n de rutina en todas estas \u00e1reas para garantizar la presencia de personal, y que los servicios que demanda la ciudadan\u00eda sean otorgados con rapidez y calidad, mediante empleados y empleadas designadas por guardias.<\/p>\n\n\n\n<p>La supervisi\u00f3n inici\u00f3 desde las 8 de la ma\u00f1ana, horario en que la poblaci\u00f3n que acud\u00eda a realizar sus tr\u00e1mites fue atendida en cada una de las dependencias, lo cual gener\u00f3 un beneficio total facilitando el avance de solicitudes y el aprovechamiento del d\u00eda para agilizar pendientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de mantener activa la atenci\u00f3n a la ciudadan\u00eda, el Gobierno Municipal de Soledad de Graciano S\u00e1nchez garantiza la prestaci\u00f3n de servicios p\u00fablicos en sus \u00e1reas operativas, de emergencia y exilio, as\u00ed como de tr\u00e1mites fundamentales en este d\u00eda de asueto, inform\u00f3 la Contralor\u00eda Interna. Este lunes 18 de marzo, considerado como descanso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/742"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=742"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/742\/revisions"}],"predecessor-version":[{"id":744,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/742\/revisions\/744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/743"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}