{"id":795,"date":"2024-03-19T18:18:00","date_gmt":"2024-03-19T18:18:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=795"},"modified":"2024-03-20T06:20:46","modified_gmt":"2024-03-20T06:20:46","slug":"amplio-programa-por-aniversario-del-museo-leonora-carrington","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/19\/amplio-programa-por-aniversario-del-museo-leonora-carrington\/","title":{"rendered":"Amplio programa por aniversario del museo Leonora Carrington"},"content":{"rendered":"\n<ul>\n<li><strong>El viernes 22 de marzo se contar\u00e1 con la participaci\u00f3n de la Camerata de San Luis, Le Ballet Ode\u00f3n, as\u00ed como de Yoshihisa Tanaka y Ryuta Lida<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Este pr\u00f3ximo viernes 22 de marzo, el Poder Ejecutivo del Estado, a trav\u00e9s de la Secretar\u00eda de Cultura (Secult), invita a la celebraci\u00f3n del aniversario del Museo Leonora Carrington San Luis Potos\u00ed, con un programa de actividades art\u00edsticas y culturales a partir de las 18:30 horas, que incluye la Camerata de San Luis, Le Ballet Ode\u00f3n, Yoshihisa Tanaka y Ryuta Lida, con entrada libre.&nbsp;<\/p>\n\n\n\n<p>La Secult, revel\u00f3 que el programa de actividades iniciar\u00e1 a las 18:30 horas con el concierto Primavera, a cargo de la Camerata de San Luis que interpretar\u00e1 Serenata, de M. Karlowicz, as\u00ed como piezas de J.S. Bach y Tangos argentinos, en la Sala de las Musas, y despu\u00e9s la compa\u00f1\u00eda potosina Le Ballet Ode\u00f3n ofrecer\u00e1 una presentaci\u00f3n danc\u00edstica especial.<\/p>\n\n\n\n<p>Adicionalmente, a las 19:20 en la Sala de las Musas, se invita al p\u00fablico a ser part\u00edcipes de la pl\u00e1tica con Yoshihisa Tanaka y Ryuta Lida, para posteriormente presenciar la inauguraci\u00f3n de su exposici\u00f3n temporal \u00abNERHOL: Beyond the Way\u00bb, que tendr\u00e1 lugar en los patios y salas temporales del museo, en una colaboraci\u00f3n con Fundaci\u00f3n AMMA.<\/p>\n\n\n\n<p>Todas las actividades son de entrada libre; la programaci\u00f3n completa se encuentra disponible y podr\u00e1 ser consultada a trav\u00e9s de las redes sociales del Museo Leonora Carrington y del Centro de las Artes de San Luis Potos\u00ed, en Facebook, X e Instagram. Mayores informes al (444) 1 37 41 00, en horario de lunes a viernes de 09:00 a 14:00 horas.<\/p>\n\n\n\n<p>Esta informaci\u00f3n es de inter\u00e9s p\u00fablico, ajena a cualquier inter\u00e9s particular o alg\u00fan partido pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este pr\u00f3ximo viernes 22 de marzo, el Poder Ejecutivo del Estado, a trav\u00e9s de la Secretar\u00eda de Cultura (Secult), invita a la celebraci\u00f3n del aniversario del Museo Leonora Carrington San Luis Potos\u00ed, con un programa de actividades art\u00edsticas y culturales a partir de las 18:30 horas, que incluye la Camerata de San Luis, Le Ballet [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/795"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=795"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/795\/revisions"}],"predecessor-version":[{"id":796,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/795\/revisions\/796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/793"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}