{"id":864,"date":"2024-03-21T10:03:00","date_gmt":"2024-03-21T10:03:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=864"},"modified":"2024-03-21T23:06:02","modified_gmt":"2024-03-21T23:06:02","slug":"con-empatia-seguiremos-disminuyendo-la-pobreza-ruth-gonzalez","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/21\/con-empatia-seguiremos-disminuyendo-la-pobreza-ruth-gonzalez\/","title":{"rendered":"Con empat\u00eda seguiremos disminuyendo la pobreza: Ruth Gonz\u00e1lez"},"content":{"rendered":"\n<ul>\n<li><strong>Desde el Senado de la Rep\u00fablica la candidata del Partido Verde gestionar\u00e1 proyectos de inversi\u00f3n para colonias marginales de la capital potosina<\/strong><\/li>\n<\/ul>\n\n\n\n<p>En una acci\u00f3n de empat\u00eda y solidaridad, Ruth Gonz\u00e1lez Silva, candidata del Partido Verde Ecologista de Mexico (PVEM) al Senado de la Rep\u00fablica, anunci\u00f3 que gestionar\u00e1 proyectos para sacar de la marginaci\u00f3n a colonias de la capital potosina, condenadas por la herencia maldita al olvido y el atraso.<\/p>\n\n\n\n<p>\u201cMi experiencia al frente del DIF Estatal me llev\u00f3 a recorrer las colonias de la capital potosina, conozco las necesidades de los habitantes y el abandono que sufren, por ello haremos proyectos para que cada municipio impulse el desarrollo de las familias\u201d, declar\u00f3.<\/p>\n\n\n\n<p>En su vig\u00e9simo d\u00eda de la campa\u00f1a senatorial, la candidata del Partido Verde Ecologista de Mexico (PVEM) se reuni\u00f3 con vecinos de las colonias Morales y Mezquital Wenceslao, a quienes escuch\u00f3 sus necesidades y peticiones.<\/p>\n\n\n\n<p>\u201cLa mayor problem\u00e1tica de las colonias populares en la capital potosina se originan por la falta o deficiencia de los servicios municipales, por lo que el apoyo total para que \u00e1reas recreativas, estancias infantiles y obras de infraestructura se construyan en la capital y todos los municipios\u00bb, dijo Ruth Gonz\u00e1lez.<\/p>\n\n\n\n<p>La aspirante al Senado hizo un llamado a la poblaci\u00f3n para que el pr\u00f3ximo 2 de junio acudan a las urnas y voten por las y los candidatos del Partido Verde para garantizar la transformaci\u00f3n de San Luis Potos\u00ed, iniciada hace dos a\u00f1os con el Gobierno del cambio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una acci\u00f3n de empat\u00eda y solidaridad, Ruth Gonz\u00e1lez Silva, candidata del Partido Verde Ecologista de Mexico (PVEM) al Senado de la Rep\u00fablica, anunci\u00f3 que gestionar\u00e1 proyectos para sacar de la marginaci\u00f3n a colonias de la capital potosina, condenadas por la herencia maldita al olvido y el atraso. \u201cMi experiencia al frente del DIF Estatal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[13],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/864"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=864"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/864\/revisions"}],"predecessor-version":[{"id":866,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/864\/revisions\/866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/865"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}