{"id":889,"date":"2024-03-22T16:14:00","date_gmt":"2024-03-22T16:14:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=889"},"modified":"2024-03-23T01:16:49","modified_gmt":"2024-03-23T01:16:49","slug":"sspc-de-la-capital-implementara-operativo-vial-por-arranque-del-festival-san-luis-en-primavera","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/22\/sspc-de-la-capital-implementara-operativo-vial-por-arranque-del-festival-san-luis-en-primavera\/","title":{"rendered":"SSPC de la Capital implementar\u00e1 operativo vial por arranque del Festival San Luis en Primavera"},"content":{"rendered":"\n<p>La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), a trav\u00e9s de la Direcci\u00f3n General de Polic\u00eda Vial y Movilidad, implementar\u00e1 un operativo vial con motivo del Festival San Luis en Primavera, a realizarse en las principales plazas p\u00fablicas del Centro Hist\u00f3rico del 23 al 31 de marzo.<\/p>\n\n\n\n<p>Para facilitar el acceso a los espect\u00e1culos a realizarse en el Festival San Luis en Primavera, la Direcci\u00f3n General de Polic\u00eda Vial prev\u00e9 el cierre al tr\u00e1nsito vehicular diariamente, a partir de las 19:00 horas, excepto para los d\u00edas 29 y 31 de marzo, que no habr\u00e1 evento en Plaza de Aranzaz\u00fa.<\/p>\n\n\n\n<p>En Plaza de los Fundadores se contempla el cierre vial \u2013a partir de la hora mencionada- en las avenidas Venustiano Carranza, en el tramo de la avenida Reforma a la Plaza de los Fundadores; Dami\u00e1n Carmona, en el tramo de Juli\u00e1n de los Reyes a la Plaza de los Fundadores; la calle D\u00edaz de Le\u00f3n, en el tramo de Iturbide a la Plaza de los Fundadores y&nbsp; \u00c1lvaro Obreg\u00f3n, en el tramo de Escobedo a la Plaza de los Fundadores.<\/p>\n\n\n\n<p>En este punto, los d\u00edas 28, 29 y 30 de marzo permanecer\u00e1 cerrada la calle \u00c1lvaro Obreg\u00f3n en el tramo de Allende a Dami\u00e1n Carmona, en virtud de que permanecer\u00e1 estacionada una gr\u00faa que ser\u00e1 utilizada para el show a\u00e9reo del d\u00eda 30 de marzo.<\/p>\n\n\n\n<p>Para el acceso peatonal a la Plaza del Carmen, se prev\u00e9 el cierre vial en las calles Manuel J. Oth\u00f3n, en el tramo de 20 de Noviembre a la calle Juan Sarabia y Los Bravo, en el tramo de 20 de noviembre a la calle Morelos.<\/p>\n\n\n\n<p>Para los espect\u00e1culos que se desarrollar\u00e1n en Plaza de Aranzaz\u00fa, la Polic\u00eda Vial realizar\u00e1 el cierre vial en la calle Independencia, en el tramo de Juli\u00e1n de los Reyes a calle Galeana y en Melchor Ocampo, en el tramo de avenida Reforma a Independencia.<\/p>\n\n\n\n<p><a><\/a>Para la Plaza de los Fundadores se prev\u00e9 restricciones de estacionamiento en las calles \u00c1lvaro Obreg\u00f3n, en el tramo de Aldama a Independencia, Venustiano Carranza en el tramo de Independencia a Aldama y Dami\u00e1n Carmona en el tramo de \u00c1lvaro Obreg\u00f3n a Mariano Arista. En la Plaza Aranzaz\u00fa se restringir\u00e1 el estacionamiento en la calle de Galeana, frente al Museo Regional Potosino.<\/p>\n\n\n\n<p>Se comparte esta informaci\u00f3n por su relevancia para el p\u00fablico en general; no est\u00e1 influenciada por intereses individuales o afiliaciones pol\u00edticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), a trav\u00e9s de la Direcci\u00f3n General de Polic\u00eda Vial y Movilidad, implementar\u00e1 un operativo vial con motivo del Festival San Luis en Primavera, a realizarse en las principales plazas p\u00fablicas del Centro Hist\u00f3rico del 23 al 31 de marzo. Para facilitar el acceso a los espect\u00e1culos a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/889"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=889"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/889\/revisions"}],"predecessor-version":[{"id":891,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/889\/revisions\/891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/890"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}