{"id":937,"date":"2024-03-23T14:08:00","date_gmt":"2024-03-23T14:08:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=937"},"modified":"2024-03-24T03:41:08","modified_gmt":"2024-03-24T03:41:08","slug":"proteccion-civil-de-soledad-tiene-preparado-operativo-fenae-2024","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/03\/23\/proteccion-civil-de-soledad-tiene-preparado-operativo-fenae-2024\/","title":{"rendered":"Protecci\u00f3n Civil de Soledad tiene preparado operativo Fenae 2024"},"content":{"rendered":"\n<ul>\n<li><strong>Con la participaci\u00f3n de 70 elementos municipales, se garantizar\u00e1 la seguridad en todas las \u00e1reas de la Feria Nacional de la Enchilada.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con la finalidad de salvaguardar la integridad de las y los visitantes locales, nacionales y extranjeros a la Feria Nacional de la Enchilada (FENAE 2024), el Gobierno Municipal de Soledad de Graciano S\u00e1nchez, mediante la Coordinaci\u00f3n de Protecci\u00f3n Civil, ya cuenta con un plan operativo de prevenci\u00f3n que se aplicar\u00e1 en este importante evento que se celebrar\u00e1 del 30 de marzo al 7 de abril.<\/p>\n\n\n\n<p>Para mantener la vigilancia en todas las \u00e1reas, se contar\u00e1 con un estado de fuerza de 70 elementos quienes mantendr\u00e1n coordinaci\u00f3n con otros grupos de rescate, como 14 param\u00e9dicos voluntarios, as\u00ed como dos ambulancias, cinco veh\u00edculos de emergencia, cuatro motocicletas, y se instalar\u00e1n tres m\u00f3dulos para atender cualquier contingencia que pudiera presentarse. Tambi\u00e9n habr\u00e1 colaboraci\u00f3n con la Direcci\u00f3n General de Seguridad P\u00fablica Municipal.<\/p>\n\n\n\n<p>Adem\u00e1s, se realizar\u00e1n inspecciones exhaustivas de comercios, juegos mec\u00e1nicos e instalaciones de todas las \u00e1reas de la feria, con el objetivo de garantizar que cumplan con medidas b\u00e1sicas de seguridad, como son las conexiones el\u00e9ctricas, tanques de gas, extintores y funcionamiento general.<\/p>\n\n\n\n<p>Para las y los asistentes a los conciertos que se celebrar\u00e1n en el Teatro del Pueblo, se solicita evitar llegar con varias horas de anticipaci\u00f3n para prevenir casos de deshidrataci\u00f3n, ante las altas temperaturas que se est\u00e1n registrando en la entidad, o en su defecto, portar una botella de agua, as\u00ed mismo se solicita evitar ingresar al evento con paraguas, ya que representan un riesgo para asistentes a eventos multitudinarios.<\/p>\n\n\n\n<p>Asimismo, se plane\u00f3 un operativo especial para la novena Carrera Atl\u00e9tica de la Enchilada que se efectuar\u00e1 este domingo, en el que participar\u00e1n los elementos de Protecci\u00f3n Civil a trav\u00e9s de unidades motorizadas que estar\u00e1n dando seguimiento a los participantes a fin de darles atenci\u00f3n y prevenir incidencias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la finalidad de salvaguardar la integridad de las y los visitantes locales, nacionales y extranjeros a la Feria Nacional de la Enchilada (FENAE 2024), el Gobierno Municipal de Soledad de Graciano S\u00e1nchez, mediante la Coordinaci\u00f3n de Protecci\u00f3n Civil, ya cuenta con un plan operativo de prevenci\u00f3n que se aplicar\u00e1 en este importante evento que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/937"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=937"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/937\/revisions"}],"predecessor-version":[{"id":939,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/937\/revisions\/939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/938"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}