{"id":9851,"date":"2024-10-19T12:40:00","date_gmt":"2024-10-19T12:40:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=9851"},"modified":"2024-10-19T20:17:26","modified_gmt":"2024-10-19T20:17:26","slug":"instalan-comision-permanente-de-asuntos-metropolitanos-en-el-cabildo-de-la-capital","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/10\/19\/instalan-comision-permanente-de-asuntos-metropolitanos-en-el-cabildo-de-la-capital\/","title":{"rendered":"Instalan Comisi\u00f3n Permanente de Asuntos Metropolitanos en el Cabildo de la Capital"},"content":{"rendered":"\n<ul>\n<li><strong>Su objetivo es atender los desaf\u00edos de una metr\u00f3poli en constante crecimiento y transformaci\u00f3n, afirm\u00f3 el Presidente de la Comisi\u00f3n, Edgardo Jasso Puente.<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Con el firme prop\u00f3sito de actualizar integralmente el marco normativo para ampliar las facultades municipales, adecu\u00e1ndolas a los retos urbanos actuales y darle herramientas m\u00e1s efectivas para enfrentar los desaf\u00edos de una metr\u00f3poli en constante crecimiento y transformaci\u00f3n, se instal\u00f3 formalmente la Comisi\u00f3n Permanente de Asuntos Metropolitanos del Ayuntamiento de San Luis Potos\u00ed, encabezada por el Regidor Rodolfo Edgardo Jasso Puente.<\/p>\n\n\n\n<p>Jasso Puente anunci\u00f3 su compromiso firme con la sustentabilidad ambiental y la resiliencia urbana, que ser\u00e1n ejes transversales en todos los proyectos y decisiones de la Comisi\u00f3n. \u201cEste enfoque refleja la creciente necesidad de abordar los retos del cambio clim\u00e1tico y promover un desarrollo urbano m\u00e1s armonioso con el medio ambiente\u201c, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Dijo que se buscar\u00e1 fortalecer los mecanismos de coordinaci\u00f3n intermunicipal para abordar de manera conjunta los desaf\u00edos, que trascienden las fronteras municipales y establecer alianzas estrat\u00e9gicas y canales de comunicaci\u00f3n m\u00e1s efectivos con los municipios vecinos, reconociendo que muchos de los problemas urbanos requieren soluciones coordinadas a nivel metropolitano.<\/p>\n\n\n\n<p>Destac\u00f3 tambi\u00e9n la importancia de la innovaci\u00f3n tecnol\u00f3gica como herramienta fundamental para mejorar la gesti\u00f3n urbana, hacer m\u00e1s eficientes los servicios p\u00fablicos y mejorar la calidad de vida de los ciudadanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el firme prop\u00f3sito de actualizar integralmente el marco normativo para ampliar las facultades municipales, adecu\u00e1ndolas a los retos urbanos actuales y darle herramientas m\u00e1s efectivas para enfrentar los desaf\u00edos de una metr\u00f3poli en constante crecimiento y transformaci\u00f3n, se instal\u00f3 formalmente la Comisi\u00f3n Permanente de Asuntos Metropolitanos del Ayuntamiento de San Luis Potos\u00ed, encabezada por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9851"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=9851"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9851\/revisions"}],"predecessor-version":[{"id":9853,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9851\/revisions\/9853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/9852"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=9851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=9851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=9851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}