{"id":9965,"date":"2024-10-22T13:40:00","date_gmt":"2024-10-22T13:40:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=9965"},"modified":"2024-10-23T00:56:28","modified_gmt":"2024-10-23T00:56:28","slug":"villa-de-pozos-instala-comision-de-transparencia","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/10\/22\/villa-de-pozos-instala-comision-de-transparencia\/","title":{"rendered":"Villa de Pozos instala Comisi\u00f3n de Transparencia"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La instalaci\u00f3n de la comisi\u00f3n destaca el compromiso del municipio con la transparencia y la buena gobernanza.<\/strong><\/p>\n\n\n\n<p>El Concejo Municipal de Villa de Pozos ha dado un paso significativo en su compromiso con la transparencia y la rendici\u00f3n de cuentas al instalar oficialmente la Comisi\u00f3n de Transparencia y Acceso a la Informaci\u00f3n.<\/p>\n\n\n\n<p>El presidente de dicha comisi\u00f3n Gerardo \u00c1vila Rodr\u00edguez destac\u00f3 la importancia de la transparencia en el municipio, como un pilar de la democracia y la buena gobernanza; Durante la ceremonia de instalaci\u00f3n, asisti\u00f3 como testigo de este ejercicio, la comisionada numeraria de la Comisi\u00f3n Estatal de Garant\u00eda de Acceso a la Informaci\u00f3n P\u00fablica (Cegaip), Sara Viridiana Tapia Rinc\u00f3n.&nbsp;<\/p>\n\n\n\n<p>El Secretario General del municipio, Ren\u00e9 Oyarvide Ibarra destac\u00f3 que&nbsp; la comisi\u00f3n de Transparencia estar\u00e1 conformada por representantes de diversas \u00e1reas del Concejo Municipal, lo que permitir\u00e1 una visi\u00f3n integral sobre las necesidades y expectativas de la poblaci\u00f3n en materia de acceso a la informaci\u00f3n.<\/p>\n\n\n\n<p>Con esta iniciativa, Villa de Pozos se posiciona como un municipio proactivo en la promoci\u00f3n de la transparencia y da&nbsp; paso hacia la construcci\u00f3n de un gobierno m\u00e1s accesible y responsable, que busca involucrar a la ciudadan\u00eda en la toma de decisiones y asegurar que la informaci\u00f3n p\u00fablica est\u00e9 al alcance de todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La instalaci\u00f3n de la comisi\u00f3n destaca el compromiso del municipio con la transparencia y la buena gobernanza. El Concejo Municipal de Villa de Pozos ha dado un paso significativo en su compromiso con la transparencia y la rendici\u00f3n de cuentas al instalar oficialmente la Comisi\u00f3n de Transparencia y Acceso a la Informaci\u00f3n. El presidente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[15],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9965"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=9965"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9965\/revisions"}],"predecessor-version":[{"id":9967,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9965\/revisions\/9967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/9966"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=9965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=9965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=9965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}