{"id":9982,"date":"2024-10-23T10:00:00","date_gmt":"2024-10-23T10:00:00","guid":{"rendered":"https:\/\/smnoticias.com.mx\/?p=9982"},"modified":"2024-10-23T16:57:55","modified_gmt":"2024-10-23T16:57:55","slug":"proteccion-civil-amplia-apoyo-a-las-y-los-potosinos-ante-bajas-temperaturas","status":"publish","type":"post","link":"https:\/\/smnoticias.com.mx\/index.php\/2024\/10\/23\/proteccion-civil-amplia-apoyo-a-las-y-los-potosinos-ante-bajas-temperaturas\/","title":{"rendered":"Protecci\u00f3n Civil ampl\u00eda apoyo a las y los potosinos ante bajas temperaturas"},"content":{"rendered":"\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Trabaja con ayuntamientos para llevar a personas en situaci\u00f3n de vulnerabilidad a los refugios temporales instalados en las cuatro regiones<\/strong><\/p>\n\n\n\n<p>La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC), dio a conocer que de acuerdo con el Servicio Meteorol\u00f3gico Nacional (SMN), durante los \u00faltimos d\u00edas habr\u00e1 un descenso de las temperaturas, as\u00ed como la presencia de algunas lluvias puntuales en las cuatro regiones de San Luis Potos\u00ed, por lo que colabora con los ayuntamientos para acercar m\u00e1s apoyo a las y los potosinos, principalmente a quienes est\u00e1n en situaci\u00f3n de vulnerabilidad, con refugios temporales en las cuatro regiones.<\/p>\n\n\n\n<p>El director de la dependencia, Mauricio Ordaz Flores, se\u00f1al\u00f3 que, por instrucci\u00f3n del Gobernador Ricardo Gallardo Cardona, la dependencia contin\u00faa con el apoyo y resguardo de las personas en situaci\u00f3n de calle o vulnerables, derivado de la presencia de frentes fr\u00edos, al informar que el fin de semana se trasladaron a 36 personas a refugios instalados en los 59 municipios.<\/p>\n\n\n\n<p>Destac\u00f3 la coordinaci\u00f3n con las direcciones municipales de protecci\u00f3n civil, que comunican las emergencias y atenciones, por lo que en esta temporada invernal reportan las personas que son llevadas a los refugios que debidamente tienen instalados en sus municipios y donde les proporcionan techo donde resguardarse, alimentaci\u00f3n y atenci\u00f3n m\u00e9dica en caso de requerirlo.<\/p>\n\n\n\n<p>Finalmente, coment\u00f3 que para esta temporada se pronostican temperaturas muy fr\u00edas, por lo que ya trabaja con el municipio de Catorce donde, a\u00f1o con a\u00f1o, el term\u00f3metro registra los niveles m\u00e1s bajos incluso hasta nevadas, para llevar apoyos invernales a la poblaci\u00f3n m\u00e1s vulnerable, adem\u00e1s de que recomend\u00f3 evitar que turistas realicen campismo ante bajas temperaturas, ya que pueden comprometer su salud e incluso sufrir hipotermia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Trabaja con ayuntamientos para llevar a personas en situaci\u00f3n de vulnerabilidad a los refugios temporales instalados en las cuatro regiones La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC), dio a conocer que de acuerdo con el Servicio Meteorol\u00f3gico Nacional (SMN), durante los \u00faltimos d\u00edas habr\u00e1 un descenso de las temperaturas, as\u00ed como la presencia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[3],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9982"}],"collection":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=9982"}],"version-history":[{"count":1,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9982\/revisions"}],"predecessor-version":[{"id":9984,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9982\/revisions\/9984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/9983"}],"wp:attachment":[{"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=9982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=9982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smnoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=9982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}